{"id":10695,"date":"2017-11-08T15:12:29","date_gmt":"2017-11-08T12:12:29","guid":{"rendered":"http:\/\/madamebulgaria.com\/?p=10695"},"modified":"2017-12-03T19:28:43","modified_gmt":"2017-12-03T16:28:43","slug":"12a-edizione-delle-giornate-belghe-in-bulgaria","status":"publish","type":"post","link":"https:\/\/madamebulgaria.com\/it\/12a-edizione-delle-giornate-belghe-in-bulgaria\/","title":{"rendered":"12a edizione delle Giornate belghe in Bulgaria"},"content":{"rendered":"<h4>Dal 6 al 10 novembre 2017, il Business Club Belgio-Lussemburgo e l'Ambasciata del Regno del Belgio in Bulgaria organizzano la 12\u00aa edizione delle Giornate belghe in Bulgaria. Per saperne di pi\u00f9 su queste giornate molto speciali.<\/h4>\n<p>Le Giornate belghe in Bulgaria sono diventate un evento annuale tradizionale nel calendario di ogni azienda e persona sia belga che bulgara. In questa occasione molto speciale, bulgari e belgi si scambiano le loro esperienze e i loro progetti di cooperazione fruttuosa in uno spirito di solida amicizia, godendo della cultura belga. Inoltre, ogni investitore belga membro del club pu\u00f2 organizzare un evento aziendale per promuovere le proprie attivit\u00e0 e invitare ospiti speciali, contribuendo in tal modo alla realizzazione di un progetto di cooperazione.<span lang=\"en\">\u00a0per rendere questi pochi giorni un piacevole appuntamento.<\/span><\/p>\n<p>Patron della campagna \u00e8 l'ambasciatore del Regno del Belgio in Bulgaria, Sua Eccellenza Fran\u00e7ois Bontemps. Il festival di quest'anno, intitolato \u201cScambio di competenze e know-how\u201d, \u00e8 stato inaugurato il 6 novembre con un concerto classico dell'ensemble da camera \u201cArbanassi\u201d. Questa nuova edizione arriva con un nuovo focus e un nuovo motto: Fun, Food and Know-How, e questa volta il networking sar\u00e0 il mantra.<\/p>\n<figure id=\"attachment_10789\" aria-describedby=\"caption-attachment-10789\" style=\"width: 1110px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-10789 size-full lazyload\" title=\"Giorni belgi in Bulgaria\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-src=\"http:\/\/madamebulgaria.com\/wp-content\/uploads\/2017\/11\/Capture-d\u2019\u00e9cran-2017-11-08-\u00e0-15.02.50.png\" alt=\"Giorni belgi in Bulgaria\" width=\"1110\" height=\"373\" data-sizes=\"auto\" data-srcset=\"https:\/\/madamebulgaria.com\/wp-content\/uploads\/2017\/11\/Capture-d\u2019\u00e9cran-2017-11-08-\u00e0-15.02.50.png 1110w, https:\/\/madamebulgaria.com\/wp-content\/uploads\/2017\/11\/Capture-d\u2019\u00e9cran-2017-11-08-\u00e0-15.02.50-300x101.png 300w, https:\/\/madamebulgaria.com\/wp-content\/uploads\/2017\/11\/Capture-d\u2019\u00e9cran-2017-11-08-\u00e0-15.02.50-768x258.png 768w, https:\/\/madamebulgaria.com\/wp-content\/uploads\/2017\/11\/Capture-d\u2019\u00e9cran-2017-11-08-\u00e0-15.02.50-1024x344.png 1024w, https:\/\/madamebulgaria.com\/wp-content\/uploads\/2017\/11\/Capture-d\u2019\u00e9cran-2017-11-08-\u00e0-15.02.50-600x202.png 600w\" sizes=\"auto, (max-width: 1110px) 100vw, 1110px\" \/><figcaption id=\"caption-attachment-10789\" class=\"wp-caption-text\">@Giornate Belghe in Bulgaria, Galleria San Stefano - Sofia<\/figcaption><\/figure>\n<p>La parte centrale dell'iniziativa dedicata al business si \u00e8 svolta ieri, 7 novembre. Si \u00e8 tenuto un dibattito sul tema \u201cBusiness, scambio di competenze e know-how\u201d, seguito da brevi presentazioni delle aziende partecipanti al premio per i premi aziendali \u201cPrimus Inter Pares\u201d 2017, che ogni anno viene assegnato dalla comunit\u00e0 imprenditoriale belga per i contributi allo sviluppo delle relazioni tra Bulgaria e Belgio.<\/p>\n<figure id=\"attachment_10787\" aria-describedby=\"caption-attachment-10787\" style=\"width: 1920px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-10787 size-full lazyload\" title=\"Giornate belghe in Bulgaria 2017\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-src=\"http:\/\/madamebulgaria.com\/wp-content\/uploads\/2017\/11\/DSC_0190.jpg\" alt=\"Giornate belghe in Bulgaria 2017\" width=\"1920\" height=\"1281\" \/><figcaption id=\"caption-attachment-10787\" class=\"wp-caption-text\">@Giornate Belghe in Bulgaria, Galleria San Stefano - Sofia<\/figcaption><\/figure>\n<figure id=\"attachment_10793\" aria-describedby=\"caption-attachment-10793\" style=\"width: 1138px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-10793 size-full lazyload\" title=\"Giornate belghe in Bulgaria 2017\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-src=\"http:\/\/madamebulgaria.com\/wp-content\/uploads\/2017\/11\/Capture-d\u2019\u00e9cran-2017-11-08-\u00e0-15.13.16.png\" alt=\"Giornate belghe in Bulgaria 2017\" width=\"1138\" height=\"537\" data-sizes=\"auto\" data-srcset=\"https:\/\/madamebulgaria.com\/wp-content\/uploads\/2017\/11\/Capture-d\u2019\u00e9cran-2017-11-08-\u00e0-15.13.16.png 1138w, https:\/\/madamebulgaria.com\/wp-content\/uploads\/2017\/11\/Capture-d\u2019\u00e9cran-2017-11-08-\u00e0-15.13.16-300x142.png 300w, https:\/\/madamebulgaria.com\/wp-content\/uploads\/2017\/11\/Capture-d\u2019\u00e9cran-2017-11-08-\u00e0-15.13.16-768x362.png 768w, https:\/\/madamebulgaria.com\/wp-content\/uploads\/2017\/11\/Capture-d\u2019\u00e9cran-2017-11-08-\u00e0-15.13.16-1024x483.png 1024w, https:\/\/madamebulgaria.com\/wp-content\/uploads\/2017\/11\/Capture-d\u2019\u00e9cran-2017-11-08-\u00e0-15.13.16-600x283.png 600w\" sizes=\"auto, (max-width: 1138px) 100vw, 1138px\" \/><figcaption id=\"caption-attachment-10793\" class=\"wp-caption-text\">@Giornate Belghe in Bulgaria, Galleria San Stefano - Sofia<\/figcaption><\/figure>\n<p>Alla fine della serata la giuria ha annunciato i vincitori del concorso. Il primo posto \u00e8 stato assegnato all'azienda DSN che, secondo il pubblico della giuria Marie, ha presentato la presentazione pi\u00f9 stimolante. Il secondo posto \u00e8 stato assegnato a Melexis e il terzo a Solvay Sodi.<\/p>\n<figure id=\"attachment_10788\" aria-describedby=\"caption-attachment-10788\" style=\"width: 1920px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-10788 size-full lazyload\" title=\"Giornate belghe in Bulgaria 2017\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-src=\"http:\/\/madamebulgaria.com\/wp-content\/uploads\/2017\/11\/DSC_0375.jpg\" alt=\"Giornate belghe in Bulgaria 2017\" width=\"1920\" height=\"1281\" \/><figcaption id=\"caption-attachment-10788\" class=\"wp-caption-text\">@Giornate Belghe in Bulgaria, Galleria San Stefano - Sofia<\/figcaption><\/figure>\n<p>L'evento Giorni belgi in Bulgaria proporr\u00e0 un programma di eventi vari che mescolano affari, comunicazione e buon gusto. La degustazione di cioccolato belga e vino bulgaro rilasser\u00e0 i sensi l'8 novembre, mentre a seguire \u00e8 prevista l'esibizione di una parte delle aziende del BBL Business Club. L'ultima serata della serie di eventi offrir\u00e0 puro intrattenimento per la comunit\u00e0 imprenditoriale. Il torneo di bowling delle squadre aziendali delle societ\u00e0 del club mira a creare contatti amichevoli e competizione tra di loro, sostenendo cos\u00ec le imprese, i loro obiettivi e lo sviluppo futuro. La partecipazione agli eventi \u00e8 solo su invito.\u00a0<span lang=\"en\">Forza, non aspettiamo oltre per ricevere un invito.\u00a0<\/span><\/p>\n<p><strong>Di pi\u00f9<\/strong> : <a href=\"http:\/\/bblbg.com\/?page_id=30\">Info sull'evento<\/a> \/ <a href=\"https:\/\/www.facebook.com\/events\/683898395144042\/\">Evento Facebook<\/a>\u00a0\/ Richieste di colloquio con S.E. Fran\u00e7ois Bontemps, Ambasciatore del Belgio : Dimitar Dzhermanski - Tel: 02\/865 05 86 - Mob .: 089 666 35 31 - E-mail: dimitar.djermanski@interimage.bg.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-10702 size-full lazyload\" title=\"Giornate belghe in Bulgaria 2017\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-src=\"http:\/\/madamebulgaria.com\/wp-content\/uploads\/2017\/11\/PRELIMINARY-PROGRAM_Belgian-Days-2017_opt.jpg\" alt=\"Giornate belghe in Bulgaria 2017\" width=\"595\" height=\"842\" data-sizes=\"auto\" data-srcset=\"https:\/\/madamebulgaria.com\/wp-content\/uploads\/2017\/11\/PRELIMINARY-PROGRAM_Belgian-Days-2017_opt.jpg 595w, https:\/\/madamebulgaria.com\/wp-content\/uploads\/2017\/11\/PRELIMINARY-PROGRAM_Belgian-Days-2017_opt-212x300.jpg 212w\" sizes=\"auto, (max-width: 595px) 100vw, 595px\" \/><\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>From 6th to 10th November, 2017, the Belgian-Bulgarian-Luxembourg Business Club and the Embassy of the Kingdom of Belgium to Bulgaria organize the 12th edition of the\u00a0Belgian Days in Bulgaria. What more about these very special days. The Belgian Days in Bulgaria become a traditional annual event in the calendar of every company and individual both&hellip;<\/p>","protected":false},"author":1,"featured_media":10785,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"footnotes":""},"categories":[462,270,464],"tags":[450,448,449,132,339,99,50],"thb-sponsors":[],"class_list":["post-10695","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-agenda","category-business-life","category-sofia-city","tag-ambassy-of-belgium","tag-belgian-days","tag-belgium","tag-event","tag-food","tag-sofia","tag-wine","post_format-post-format-image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>12th Edition Of The Belgian Days In Bulgaria &#8211; Madame Bulgaria<\/title>\n<meta name=\"description\" content=\"The Belgian Days in Bulgaria, from 6th to 10th November, 2017, become a traditional annual event in the calendar of every company and individual both...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/madamebulgaria.com\/it\/12a-edizione-delle-giornate-belghe-in-bulgaria\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"12th Edition Of The Belgian Days In Bulgaria &#8211; Madame Bulgaria\" \/>\n<meta property=\"og:description\" content=\"The Belgian Days in Bulgaria, from 6th to 10th November, 2017, become a traditional annual event in the calendar of every company and individual both...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/madamebulgaria.com\/it\/12a-edizione-delle-giornate-belghe-in-bulgaria\/\" \/>\n<meta property=\"og:site_name\" content=\"Madame Bulgaria\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/madamebulgaria\/?fref=ts\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/mariepieee?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2017-11-08T12:12:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-12-03T16:28:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/madamebulgaria.com\/wp-content\/uploads\/2017\/11\/Belgian-Days-Bulgaria-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1081\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marie Pietrzak\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@madamebulgaria\" \/>\n<meta name=\"twitter:site\" content=\"@madamebulgaria\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marie Pietrzak\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/madamebulgaria.com\/12th-edition-belgian-days-in-bulgaria\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/madamebulgaria.com\/12th-edition-belgian-days-in-bulgaria\/\"},\"author\":{\"name\":\"Marie Pietrzak\",\"@id\":\"https:\/\/madamebulgaria.com\/#\/schema\/person\/7aa9609fa82f4714913bbbe9ddfe51ad\"},\"headline\":\"12th Edition Of The Belgian Days In Bulgaria\",\"datePublished\":\"2017-11-08T12:12:29+00:00\",\"dateModified\":\"2017-12-03T16:28:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/madamebulgaria.com\/12th-edition-belgian-days-in-bulgaria\/\"},\"wordCount\":505,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/madamebulgaria.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/madamebulgaria.com\/12th-edition-belgian-days-in-bulgaria\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/madamebulgaria.com\/wp-content\/uploads\/2017\/11\/Belgian-Days-Bulgaria-.jpg\",\"keywords\":[\"Ambassy of Belgium\",\"Belgian Days\",\"Belgium\",\"Event\",\"Food\",\"Sofia\",\"Wine\"],\"articleSection\":[\"Agenda\",\"Business Life\",\"Sofia City\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/madamebulgaria.com\/12th-edition-belgian-days-in-bulgaria\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/madamebulgaria.com\/12th-edition-belgian-days-in-bulgaria\/\",\"url\":\"https:\/\/madamebulgaria.com\/12th-edition-belgian-days-in-bulgaria\/\",\"name\":\"12th Edition Of The Belgian Days In Bulgaria &#8211; Madame Bulgaria\",\"isPartOf\":{\"@id\":\"https:\/\/madamebulgaria.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/madamebulgaria.com\/12th-edition-belgian-days-in-bulgaria\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/madamebulgaria.com\/12th-edition-belgian-days-in-bulgaria\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/madamebulgaria.com\/wp-content\/uploads\/2017\/11\/Belgian-Days-Bulgaria-.jpg\",\"datePublished\":\"2017-11-08T12:12:29+00:00\",\"dateModified\":\"2017-12-03T16:28:43+00:00\",\"description\":\"The Belgian Days in Bulgaria, from 6th to 10th November, 2017, become a traditional annual event in the calendar of every company and individual both...\",\"breadcrumb\":{\"@id\":\"https:\/\/madamebulgaria.com\/12th-edition-belgian-days-in-bulgaria\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/madamebulgaria.com\/12th-edition-belgian-days-in-bulgaria\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/madamebulgaria.com\/12th-edition-belgian-days-in-bulgaria\/#primaryimage\",\"url\":\"https:\/\/madamebulgaria.com\/wp-content\/uploads\/2017\/11\/Belgian-Days-Bulgaria-.jpg\",\"contentUrl\":\"https:\/\/madamebulgaria.com\/wp-content\/uploads\/2017\/11\/Belgian-Days-Bulgaria-.jpg\",\"width\":1081,\"height\":600,\"caption\":\"Belgian Days Bulgaria\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/madamebulgaria.com\/12th-edition-belgian-days-in-bulgaria\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/madamebulgaria.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"12th Edition Of The Belgian Days In Bulgaria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/madamebulgaria.com\/#website\",\"url\":\"https:\/\/madamebulgaria.com\/\",\"name\":\"Madame Bulgaria\",\"description\":\"Lifestyle, Culture, Food, More of Bulgaria\",\"publisher\":{\"@id\":\"https:\/\/madamebulgaria.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/madamebulgaria.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/madamebulgaria.com\/#organization\",\"name\":\"Madame Bulgaria\",\"url\":\"https:\/\/madamebulgaria.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/madamebulgaria.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/madamebulgaria.com\/wp-content\/uploads\/2017\/03\/MB-logo-final-2-3-e1513170700381-1.png\",\"contentUrl\":\"https:\/\/madamebulgaria.com\/wp-content\/uploads\/2017\/03\/MB-logo-final-2-3-e1513170700381-1.png\",\"width\":800,\"height\":500,\"caption\":\"Madame Bulgaria\"},\"image\":{\"@id\":\"https:\/\/madamebulgaria.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/madamebulgaria\/?fref=ts\",\"https:\/\/x.com\/madamebulgaria\",\"https:\/\/www.instagram.com\/madamebulgaria\/?hl=fr\",\"https:\/\/www.linkedin.com\/company\/madame-bulgaria\/\",\"https:\/\/www.youtube.com\/channel\/UCi6lmnQoBJkA-eJ4ijysIog\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/madamebulgaria.com\/#\/schema\/person\/7aa9609fa82f4714913bbbe9ddfe51ad\",\"name\":\"Marie Pietrzak\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/madamebulgaria.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e35bc4fd544b40b988805cb9ff91fdcf13945dd539c8a524d3943cd648985d2c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e35bc4fd544b40b988805cb9ff91fdcf13945dd539c8a524d3943cd648985d2c?s=96&d=mm&r=g\",\"caption\":\"Marie Pietrzak\"},\"description\":\"Marie is the founder of Madame Bulgaria. She fell in love with Bulgaria when she came for the first time for a weekend in 2012.\",\"sameAs\":[\"https:\/\/www.madamebulgaria.com\",\"https:\/\/www.facebook.com\/mariepieee?fref=ts\"],\"url\":\"https:\/\/madamebulgaria.com\/it\/author\/marie1606\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"12a edizione delle Giornate belghe in Bulgaria - Madame Bulgaria","description":"Le Giornate Belghe in Bulgaria, dal 6 al 10 novembre 2017, sono diventate un evento annuale tradizionale nel calendario di ogni azienda e individuo sia...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/madamebulgaria.com\/it\/12a-edizione-delle-giornate-belghe-in-bulgaria\/","og_locale":"it_IT","og_type":"article","og_title":"12th Edition Of The Belgian Days In Bulgaria &#8211; Madame Bulgaria","og_description":"The Belgian Days in Bulgaria, from 6th to 10th November, 2017, become a traditional annual event in the calendar of every company and individual both...","og_url":"https:\/\/madamebulgaria.com\/it\/12a-edizione-delle-giornate-belghe-in-bulgaria\/","og_site_name":"Madame Bulgaria","article_publisher":"https:\/\/www.facebook.com\/madamebulgaria\/?fref=ts","article_author":"https:\/\/www.facebook.com\/mariepieee?fref=ts","article_published_time":"2017-11-08T12:12:29+00:00","article_modified_time":"2017-12-03T16:28:43+00:00","og_image":[{"width":1081,"height":600,"url":"https:\/\/madamebulgaria.com\/wp-content\/uploads\/2017\/11\/Belgian-Days-Bulgaria-.jpg","type":"image\/jpeg"}],"author":"Marie Pietrzak","twitter_card":"summary_large_image","twitter_creator":"@madamebulgaria","twitter_site":"@madamebulgaria","twitter_misc":{"Scritto da":"Marie Pietrzak","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/madamebulgaria.com\/12th-edition-belgian-days-in-bulgaria\/#article","isPartOf":{"@id":"https:\/\/madamebulgaria.com\/12th-edition-belgian-days-in-bulgaria\/"},"author":{"name":"Marie Pietrzak","@id":"https:\/\/madamebulgaria.com\/#\/schema\/person\/7aa9609fa82f4714913bbbe9ddfe51ad"},"headline":"12th Edition Of The Belgian Days In Bulgaria","datePublished":"2017-11-08T12:12:29+00:00","dateModified":"2017-12-03T16:28:43+00:00","mainEntityOfPage":{"@id":"https:\/\/madamebulgaria.com\/12th-edition-belgian-days-in-bulgaria\/"},"wordCount":505,"commentCount":0,"publisher":{"@id":"https:\/\/madamebulgaria.com\/#organization"},"image":{"@id":"https:\/\/madamebulgaria.com\/12th-edition-belgian-days-in-bulgaria\/#primaryimage"},"thumbnailUrl":"https:\/\/madamebulgaria.com\/wp-content\/uploads\/2017\/11\/Belgian-Days-Bulgaria-.jpg","keywords":["Ambassy of Belgium","Belgian Days","Belgium","Event","Food","Sofia","Wine"],"articleSection":["Agenda","Business Life","Sofia City"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/madamebulgaria.com\/12th-edition-belgian-days-in-bulgaria\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/madamebulgaria.com\/12th-edition-belgian-days-in-bulgaria\/","url":"https:\/\/madamebulgaria.com\/12th-edition-belgian-days-in-bulgaria\/","name":"12a edizione delle Giornate belghe in Bulgaria - Madame Bulgaria","isPartOf":{"@id":"https:\/\/madamebulgaria.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/madamebulgaria.com\/12th-edition-belgian-days-in-bulgaria\/#primaryimage"},"image":{"@id":"https:\/\/madamebulgaria.com\/12th-edition-belgian-days-in-bulgaria\/#primaryimage"},"thumbnailUrl":"https:\/\/madamebulgaria.com\/wp-content\/uploads\/2017\/11\/Belgian-Days-Bulgaria-.jpg","datePublished":"2017-11-08T12:12:29+00:00","dateModified":"2017-12-03T16:28:43+00:00","description":"Le Giornate Belghe in Bulgaria, dal 6 al 10 novembre 2017, sono diventate un evento annuale tradizionale nel calendario di ogni azienda e individuo sia...","breadcrumb":{"@id":"https:\/\/madamebulgaria.com\/12th-edition-belgian-days-in-bulgaria\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/madamebulgaria.com\/12th-edition-belgian-days-in-bulgaria\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/madamebulgaria.com\/12th-edition-belgian-days-in-bulgaria\/#primaryimage","url":"https:\/\/madamebulgaria.com\/wp-content\/uploads\/2017\/11\/Belgian-Days-Bulgaria-.jpg","contentUrl":"https:\/\/madamebulgaria.com\/wp-content\/uploads\/2017\/11\/Belgian-Days-Bulgaria-.jpg","width":1081,"height":600,"caption":"Belgian Days Bulgaria"},{"@type":"BreadcrumbList","@id":"https:\/\/madamebulgaria.com\/12th-edition-belgian-days-in-bulgaria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/madamebulgaria.com\/"},{"@type":"ListItem","position":2,"name":"12th Edition Of The Belgian Days In Bulgaria"}]},{"@type":"WebSite","@id":"https:\/\/madamebulgaria.com\/#website","url":"https:\/\/madamebulgaria.com\/","name":"Signora Bulgaria","description":"Stile di vita, Cultura, Cibo, Altro della Bulgaria","publisher":{"@id":"https:\/\/madamebulgaria.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/madamebulgaria.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/madamebulgaria.com\/#organization","name":"Signora Bulgaria","url":"https:\/\/madamebulgaria.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/madamebulgaria.com\/#\/schema\/logo\/image\/","url":"https:\/\/madamebulgaria.com\/wp-content\/uploads\/2017\/03\/MB-logo-final-2-3-e1513170700381-1.png","contentUrl":"https:\/\/madamebulgaria.com\/wp-content\/uploads\/2017\/03\/MB-logo-final-2-3-e1513170700381-1.png","width":800,"height":500,"caption":"Madame Bulgaria"},"image":{"@id":"https:\/\/madamebulgaria.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/madamebulgaria\/?fref=ts","https:\/\/x.com\/madamebulgaria","https:\/\/www.instagram.com\/madamebulgaria\/?hl=fr","https:\/\/www.linkedin.com\/company\/madame-bulgaria\/","https:\/\/www.youtube.com\/channel\/UCi6lmnQoBJkA-eJ4ijysIog"]},{"@type":"Person","@id":"https:\/\/madamebulgaria.com\/#\/schema\/person\/7aa9609fa82f4714913bbbe9ddfe51ad","name":"Marie Pietrzak","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/madamebulgaria.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e35bc4fd544b40b988805cb9ff91fdcf13945dd539c8a524d3943cd648985d2c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e35bc4fd544b40b988805cb9ff91fdcf13945dd539c8a524d3943cd648985d2c?s=96&d=mm&r=g","caption":"Marie Pietrzak"},"description":"Marie \u00e8 la fondatrice di Madame Bulgaria. Si \u00e8 innamorata della Bulgaria quando \u00e8 venuta per la prima volta per un weekend nel 2012.","sameAs":["https:\/\/www.madamebulgaria.com","https:\/\/www.facebook.com\/mariepieee?fref=ts"],"url":"https:\/\/madamebulgaria.com\/it\/author\/marie1606\/"}]}},"_links":{"self":[{"href":"https:\/\/madamebulgaria.com\/it\/wp-json\/wp\/v2\/posts\/10695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/madamebulgaria.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/madamebulgaria.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/madamebulgaria.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/madamebulgaria.com\/it\/wp-json\/wp\/v2\/comments?post=10695"}],"version-history":[{"count":0,"href":"https:\/\/madamebulgaria.com\/it\/wp-json\/wp\/v2\/posts\/10695\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/madamebulgaria.com\/it\/wp-json\/wp\/v2\/media\/10785"}],"wp:attachment":[{"href":"https:\/\/madamebulgaria.com\/it\/wp-json\/wp\/v2\/media?parent=10695"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/madamebulgaria.com\/it\/wp-json\/wp\/v2\/categories?post=10695"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/madamebulgaria.com\/it\/wp-json\/wp\/v2\/tags?post=10695"},{"taxonomy":"thb-sponsors","embeddable":true,"href":"https:\/\/madamebulgaria.com\/it\/wp-json\/wp\/v2\/thb-sponsors?post=10695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}